{"id":23192,"date":"2016-03-01T10:16:08","date_gmt":"2016-03-01T13:16:08","guid":{"rendered":"http:\/\/belasflorescampinas.com.br\/?post_type=product&#038;p=23192"},"modified":"2026-01-29T16:50:30","modified_gmt":"2026-01-29T19:50:30","slug":"cesta-de-cafe-c02","status":"publish","type":"product","link":"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/","title":{"rendered":"Cesta de Caf\u00e9 &#8211; C02"},"content":{"rendered":"<p><em>*As flores podem sofrer algumas altera\u00e7\u00f5es conforme a \u00e9poca do ano e estoque, mas continuam sempre excelentes em sua cor, qualidade e frescor.<\/em><\/p>\n<p><em>*Na falta de algum item, substituiremos por outro. Qualquer d\u00favida, entre em contato.<\/em><\/p>\n<p><strong>COMPRE AGORA pelo WHATSAPP ou TELEFONE!<\/strong><\/p>\n<p><strong>Atendimento 24 horas pelo Whatsapp. Entre agora mesmo em contato e<span>\u00a0<\/span><a href=\"https:\/\/belasflorescampinas.com.br\/floricultura\/tempo-e-prazo-de-entrega\/\">agende a sua entrega<\/a>!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cesta Luxo<\/strong> Lil\u00e1s: 1 Lindo <strong>Arranjo Floral<\/strong> em tons <strong>Lil\u00e1s<\/strong>, 1 <strong>Bolinho<\/strong>, 1 <strong>Manteiga<\/strong> blister, 1 <strong>Iogurte<\/strong> integral, 1 <strong>Sucrilhos<\/strong>, 2 Tipos de <strong>P\u00e3es<\/strong>, 1 <strong>X\u00edcara ou Caneca<\/strong>, 2 Sach\u00eas de <strong>A\u00e7\u00facar<\/strong>, 1 Cacho de <strong>Uva<\/strong>, 1 <strong>Poleguinho<\/strong>, 2 Sach\u00eas de <strong>Caf\u00e9<\/strong> , 1 <strong>Leite ninho<\/strong>, 1 <strong>Suco<\/strong> 200ml, 2 <strong>Gel\u00e9ias<\/strong>, 2 <strong>Torradas<\/strong>, 2 <strong>Mel<\/strong> e 1 Cesta de vime.<\/p>\n","protected":false},"featured_media":33797,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[49],"product_tag":[],"class_list":["post-23192","product","type-product","status-publish","has-post-thumbnail","product_cat-cestas-de-cafe","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cesta de Caf\u00e9 - C02 - Floricultura 24h Belas Flores Campinas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cesta de Caf\u00e9 - C02 - Floricultura 24h Belas Flores Campinas\" \/>\n<meta property=\"og:description\" content=\"Cesta Luxo Lil\u00e1s: 1 Lindo Arranjo Floral em tons Lil\u00e1s, 1 Bolinho, 1 Manteiga blister, 1 Iogurte integral, 1 Sucrilhos, 2 Tipos de P\u00e3es, 1 X\u00edcara ou Caneca, 2 Sach\u00eas de A\u00e7\u00facar, 1 Cacho de Uva, 1 Poleguinho, 2 Sach\u00eas de Caf\u00e9 , 1 Leite ninho, 1 Suco 200ml, 2 Gel\u00e9ias, 2 Torradas, 2 Mel e 1 Cesta de vime.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/\" \/>\n<meta property=\"og:site_name\" content=\"Floricultura 24h Belas Flores Campinas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/belasfloresemcampinas\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T19:50:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-content\/uploads\/2016\/03\/Cesta-de-Cafe-C02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/produto\\\/cesta-de-cafe-c02\\\/\",\"url\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/produto\\\/cesta-de-cafe-c02\\\/\",\"name\":\"Cesta de Caf\u00e9 - C02 - Floricultura 24h Belas Flores Campinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/produto\\\/cesta-de-cafe-c02\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/produto\\\/cesta-de-cafe-c02\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Cesta-de-Cafe-C02.jpg\",\"datePublished\":\"2016-03-01T13:16:08+00:00\",\"dateModified\":\"2026-01-29T19:50:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/produto\\\/cesta-de-cafe-c02\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/produto\\\/cesta-de-cafe-c02\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/produto\\\/cesta-de-cafe-c02\\\/#primaryimage\",\"url\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Cesta-de-Cafe-C02.jpg\",\"contentUrl\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Cesta-de-Cafe-C02.jpg\",\"width\":500,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/produto\\\/cesta-de-cafe-c02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Floricultura\",\"item\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cesta de Caf\u00e9 &#8211; C02\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/#website\",\"url\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/\",\"name\":\"Floricultura Belas Flores Campinas\",\"description\":\"Floricultura Online de Buqu\u00eas, Cestas, Arranjos e Coroas F\u00fanebres - Campinas e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/#organization\",\"name\":\"Belas Flores Floricultura Campinas e Regi\u00e3o\",\"url\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/logo-belasflorescampinas.jpg\",\"contentUrl\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/logo-belasflorescampinas.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"Belas Flores Floricultura Campinas e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/belasflorescampinas.com.br\\\/floricultura\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/belasfloresemcampinas\\\/\",\"https:\\\/\\\/www.instagram.com\\\/floriculturabelasflores_\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cesta de Caf\u00e9 - C02 - Floricultura 24h Belas Flores Campinas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/","og_locale":"pt_BR","og_type":"article","og_title":"Cesta de Caf\u00e9 - C02 - Floricultura 24h Belas Flores Campinas","og_description":"Cesta Luxo Lil\u00e1s: 1 Lindo Arranjo Floral em tons Lil\u00e1s, 1 Bolinho, 1 Manteiga blister, 1 Iogurte integral, 1 Sucrilhos, 2 Tipos de P\u00e3es, 1 X\u00edcara ou Caneca, 2 Sach\u00eas de A\u00e7\u00facar, 1 Cacho de Uva, 1 Poleguinho, 2 Sach\u00eas de Caf\u00e9 , 1 Leite ninho, 1 Suco 200ml, 2 Gel\u00e9ias, 2 Torradas, 2 Mel e 1 Cesta de vime.","og_url":"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/","og_site_name":"Floricultura 24h Belas Flores Campinas","article_publisher":"https:\/\/www.facebook.com\/belasfloresemcampinas\/","article_modified_time":"2026-01-29T19:50:30+00:00","og_image":[{"width":500,"height":450,"url":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-content\/uploads\/2016\/03\/Cesta-de-Cafe-C02.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/","url":"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/","name":"Cesta de Caf\u00e9 - C02 - Floricultura 24h Belas Flores Campinas","isPartOf":{"@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/#website"},"primaryImageOfPage":{"@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/#primaryimage"},"image":{"@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/#primaryimage"},"thumbnailUrl":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-content\/uploads\/2016\/03\/Cesta-de-Cafe-C02.jpg","datePublished":"2016-03-01T13:16:08+00:00","dateModified":"2026-01-29T19:50:30+00:00","breadcrumb":{"@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/#primaryimage","url":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-content\/uploads\/2016\/03\/Cesta-de-Cafe-C02.jpg","contentUrl":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-content\/uploads\/2016\/03\/Cesta-de-Cafe-C02.jpg","width":500,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/produto\/cesta-de-cafe-c02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/belasflorescampinas.com.br\/floricultura\/"},{"@type":"ListItem","position":2,"name":"Floricultura","item":"https:\/\/belasflorescampinas.com.br\/floricultura\/shop\/"},{"@type":"ListItem","position":3,"name":"Cesta de Caf\u00e9 &#8211; C02"}]},{"@type":"WebSite","@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/#website","url":"https:\/\/belasflorescampinas.com.br\/floricultura\/","name":"Floricultura Belas Flores Campinas","description":"Floricultura Online de Buqu\u00eas, Cestas, Arranjos e Coroas F\u00fanebres - Campinas e Regi\u00e3o","publisher":{"@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/belasflorescampinas.com.br\/floricultura\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/#organization","name":"Belas Flores Floricultura Campinas e Regi\u00e3o","url":"https:\/\/belasflorescampinas.com.br\/floricultura\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/#\/schema\/logo\/image\/","url":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-content\/uploads\/2026\/07\/logo-belasflorescampinas.jpg","contentUrl":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-content\/uploads\/2026\/07\/logo-belasflorescampinas.jpg","width":1080,"height":1080,"caption":"Belas Flores Floricultura Campinas e Regi\u00e3o"},"image":{"@id":"https:\/\/belasflorescampinas.com.br\/floricultura\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/belasfloresemcampinas\/","https:\/\/www.instagram.com\/floriculturabelasflores_\/"]}]}},"_links":{"self":[{"href":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-json\/wp\/v2\/product\/23192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-json\/wp\/v2\/media\/33797"}],"wp:attachment":[{"href":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-json\/wp\/v2\/media?parent=23192"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-json\/wp\/v2\/product_brand?post=23192"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-json\/wp\/v2\/product_cat?post=23192"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/belasflorescampinas.com.br\/floricultura\/wp-json\/wp\/v2\/product_tag?post=23192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}